{"id":7227,"date":"2024-01-16T12:51:55","date_gmt":"2024-01-16T12:51:55","guid":{"rendered":"https:\/\/alunnoimmobiliare.it\/?post_type=property&#038;p=7227"},"modified":"2024-06-04T08:14:47","modified_gmt":"2024-06-04T08:14:47","slug":"casa-di-campagna-a-castelfiorentino","status":"publish","type":"property","link":"https:\/\/alunnoimmobiliare.it\/it\/property\/country-house-in-cast-fiorentino\/","title":{"rendered":"CASA DI CAMPAGNA A CASTEL FIORENTINO\u00a0"},"content":{"rendered":"<p>Sulle colline del comune di Castiglion Fiorentino, vicino a Cortona, proponiamo questo 200<\/p>\n\n\n\n<p>casale di mq. con piscina in vendita.&nbsp;<\/p>\n\n\n\n<p>L'immobile, ristrutturato nel 2023, \u00e8 incorniciato da 2.300 mq di terreno, con piante ornamentali<\/p>\n\n\n\n<p>e ulivi, che in parte viene adibito a parco dove una piscina panoramica di 6\u00d712 m<\/p>\n\n\n\n<p>con una vista mozzafiato sulle colline circostanti si trova.<\/p>\n\n\n\n<p>Il casale, con una caratteristica facciata in pietra a vista e mattoni, \u00e8<\/p>\n\n\n\n<p>distribuiti su 2 piani come segue:<\/p>\n\n\n\n<p>Al piano terra troviamo alcuni locali attualmente adibiti a ripostigli, cantina<\/p>\n\n\n\n<p>e locale lavanderia. Sempre al piano terra troviamo un ampio portico di circa 23 mq dove<\/p>\n\n\n\n<p>potrete trascorrere delle splendide serate estive.<\/p>\n\n\n\n<p>Salendo una scala esterna, si raggiunge il primo piano, dove troviamo un ampio soggiorno.<\/p>\n\n\n\n<p>con soggiorno e zona giorno con accesso a un bellissimo terrazzo di circa 23 mq, a<\/p>\n\n\n\n<p>cucina, un bagno di servizio e 4 luminose camere da letto, di cui due con bagno privato.&nbsp;<\/p>\n\n\n\n<p>I colori scelti durante la ristrutturazione sono bianco e grigio tortora, che conferiscono luminosit\u00e0 e<\/p>\n\n\n\n<p>calore alle stanze.<\/p>\n\n\n\n<p>\u00c8 stato scelto un sistema di pompe di calore per fornire riscaldamento e l'approvvigionamento idrico \u00e8 garantito da<\/p>\n\n\n\n<p>un pozzo privato profondo circa 120 m.<\/p>\n\n\n\n<p>Questa casa di campagna \u00e8 una grande opportunit\u00e0 di investimento, perfetta per essere utilizzata sia come residenza privata<\/p>\n\n\n\n<p>abitazione e come casa vacanze da offrire sul mercato come alloggio turistico<\/p>\n\n\n\n<p>struttura.<\/p>\n\n\n\n<p>Situato a soli 1 km di distanza (3 minuti di auto) dal paese dove troverete tutto il necessario<\/p>\n\n\n\n<p>servizi e strutture come supermercati, banche, negozi e stazione ferroviaria.<\/p>\n\n\n\n<p><br><br><\/p>","protected":false},"excerpt":{"rendered":"<p>On the hills of the municipality of Castiglion Fiorentino, close to Cortona, we offer this 200 sq.m. country house with swimming pool for sale.&nbsp; The property, renovated in 2023, is framed by 2,300 sq.m. of land, with ornamental plants and olive trees, which is partly used as park where a panoramic 6&#215;12 m swimming pool [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7228,"parent":0,"menu_order":0,"template":"","property_type":[13],"property_status":[23],"property_feature":[12,14,50],"property_label":[],"property_country":[59],"property_state":[60],"property_city":[64],"property_area":[15],"class_list":["post-7227","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-nearby-cortona","property_status-for-sale","property_feature-air-conditioning","property_feature-fireplace","property_feature-swimming-pool","property_country-italy","property_state-tuscany","property_city-castiglion-fiorentino","property_area-countryside"],"property_meta":{"houzez_geolocation_long":["-118.4156987"],"houzez_geolocation_lat":["34.0291269"],"_vc_post_settings":["a:1:{s:10:\"vc_grid_id\";a:0:{}}"],"fave_property_size":["264"],"fave_property_size_prefix":["m\u00b2"],"fave_property_id":["BRTCF-16M24"],"fave_property_price":["750000"],"fave_property_map":["0"],"fave_property_map_address":["Cortona - Tuscany"],"fave_property_location":["34.0291269,-118.4156987,8"],"fave_property_country":["US"],"fave_agents":["156"],"fave_additional_features_enable":["enable"],"additional_features":["a:1:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:13:\"Swimming pool\";s:29:\"fave_additional_feature_value\";s:3:\"Yes\";}}"],"fave_floor_plans_enable":["enable"],"fave_featured":["1"],"houzez_featured_listing_date":["2023-11-25 06:16:07"],"fave_agent_display_option":["agent_info"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"fave_video_image":["84"],"fave_payment_status":["not_paid"],"fave_property_map_street_view":["show"],"_dp_original":["432"],"fave_currency_info":[""],"houzez_total_property_views":["13186"],"houzez_views_by_date":["a:61:{s:10:\"10-23-2025\";i:1;s:10:\"11-17-2025\";i:1;s:10:\"12-24-2025\";i:1;s:10:\"12-26-2025\";i:1;s:10:\"12-29-2025\";i:1;s:10:\"12-31-2025\";i:1;s:10:\"01-05-2026\";i:1;s:10:\"01-09-2026\";i:1;s:10:\"02-17-2026\";i:1;s:10:\"02-18-2026\";i:1;s:10:\"03-11-2026\";i:1;s:10:\"03-18-2026\";i:1;s:10:\"03-19-2026\";i:1;s:10:\"04-11-2026\";i:1;s:10:\"04-22-2026\";i:1;s:10:\"05-02-2026\";i:2;s:10:\"05-07-2026\";i:1;s:10:\"05-09-2026\";i:1;s:10:\"05-10-2026\";i:4;s:10:\"05-11-2026\";i:1;s:10:\"05-13-2026\";i:3;s:10:\"05-14-2026\";i:1;s:10:\"05-15-2026\";i:1;s:10:\"05-17-2026\";i:5;s:10:\"05-18-2026\";i:2;s:10:\"05-22-2026\";i:2;s:10:\"05-23-2026\";i:1;s:10:\"05-26-2026\";i:1;s:10:\"05-27-2026\";i:2;s:10:\"05-31-2026\";i:1;s:10:\"06-02-2026\";i:2;s:10:\"06-03-2026\";i:5;s:10:\"06-07-2026\";i:1;s:10:\"06-08-2026\";i:1;s:10:\"06-09-2026\";i:1;s:10:\"06-10-2026\";i:3;s:10:\"06-11-2026\";i:4;s:10:\"06-12-2026\";i:1;s:10:\"06-13-2026\";i:1;s:10:\"06-14-2026\";i:1;s:10:\"06-16-2026\";i:2;s:10:\"06-17-2026\";i:2;s:10:\"06-18-2026\";i:1;s:10:\"06-20-2026\";i:1;s:10:\"06-21-2026\";i:1;s:10:\"06-23-2026\";i:1;s:10:\"06-24-2026\";i:3;s:10:\"06-25-2026\";i:3;s:10:\"06-27-2026\";i:1;s:10:\"06-28-2026\";i:3;s:10:\"06-30-2026\";i:2;s:10:\"07-01-2026\";i:1;s:10:\"07-02-2026\";i:4;s:10:\"07-03-2026\";i:3;s:10:\"07-04-2026\";i:2;s:10:\"07-05-2026\";i:2;s:10:\"07-07-2026\";i:1;s:10:\"07-08-2026\";i:3;s:10:\"07-09-2026\";i:1;s:10:\"07-11-2026\";i:1;s:10:\"07-15-2026\";i:1;}"],"houzez_recently_viewed":["2026-07-15 12:49:33"],"_houzez_expiration_date_status":["saved"],"rs_page_bg_color":[""],"houzez_manual_expire":["0"],"_edit_lock":["1717488888:1"],"_edit_last":["1"],"fave_energy_class":["F"],"fave_renewable_energy_global_index":["92.42 kWh \/ m\u00b2a | Energy class E"],"fave_energy_global_index":["92.42 kWh \/ m\u00b2a | Energy class B"],"fave_prop_homeslider":["yes"],"fave_property_price_prefix":["Only"],"_aioseo_title":[null],"_aioseo_description":[null],"_aioseo_keywords":["a:0:{}"],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[null],"_aioseo_og_article_tags":["a:0:{}"],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"fave_property_land_postfix":["m\u00b2"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["3"],"_thumbnail_id":["7228"],"fave_property_land":["2300"],"_wp_page_template":["default"],"fave_show_price_placeholder":["0"],"_monsterinsights_sitenote_active":["0"],"fave_property_garage_size":["0"],"fave_property_images":["7228","7229","7230","7231","7232","7233","7234","7235","7236","7237","7238","7239","7240","7241","7242","7243","7244","7245","7246","7247","7248","7249","7250","7251","7252","7253","7254","7255","7256","7257","7258","7259","7260","7261","7262","7263","7264","7265","7266","7267","7268"],"wcf_post_views_count":["68"],"aae_trending_score":["34"],"wcf_addon_custom_fonts":["a:0:{}"],"rank_math_internal_links_processed":["1"],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/properties\/7227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/properties\/7227\/revisions"}],"predecessor-version":[{"id":7269,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/properties\/7227\/revisions\/7269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/media\/7228"}],"wp:attachment":[{"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/media?parent=7227"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/property_type?post=7227"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/property_status?post=7227"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/property_feature?post=7227"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/property_label?post=7227"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/property_country?post=7227"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/property_state?post=7227"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/property_city?post=7227"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/alunnoimmobiliare.it\/it\/wp-json\/wp\/v2\/property_area?post=7227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}